{"id":1740,"date":"2024-02-26T16:25:11","date_gmt":"2024-02-26T15:25:11","guid":{"rendered":"https:\/\/amp-hplb-lille.com\/?page_id=1740"},"modified":"2026-02-25T11:02:28","modified_gmt":"2026-02-25T10:02:28","slug":"formulaire-femme-seule","status":"publish","type":"page","link":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/","title":{"rendered":"Formulaire femme seule"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1740\" class=\"elementor elementor-1740\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50e1b6f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"50e1b6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad0dbe5\" data-id=\"ad0dbe5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d94d1db elementor-widget elementor-widget-shortcode\" data-id=\"d94d1db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='fluentform ff-default fluentform_wrapper_10 ffs_default_wrap'><form data-form_id=\"10\" id=\"fluentform_10\" class=\"frm-fluent-form fluent_form_10 ff-el-form-top ff_form_instance_10_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_10_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Formulaire - Femme seule<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='1740' \/><input type=\"hidden\" id=\"_fluentform_10_fluentformnonce\" name=\"_fluentform_10_fluentformnonce\" value=\"7d795aa796\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/1740\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_names_first_name_' id='label_ff_10_names_first_name_' >Pr\u00e9nom <\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_10_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Pr\u00e9nom\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_names_last_name_' id='label_ff_10_names_last_name_' >Nom<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_10_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Nom\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_datetime_2' id='label_ff_10_datetime_2' aria-label=\"Date de naissance\">Date de naissance <\/label><\/div><div class='ff-el-input--content'><input  aria-label='Date de naissance  Use arrow keys to navigate dates. Press enter to select a date.'  aria-haspopup='dialog' data-type-datepicker data-format='d\/m\/Y' type=\"text\" name=\"datetime_2\" id=\"ff_10_datetime_2\" class=\"ff-el-form-control ff-el-datepicker\" placeholder=\"Date de naissance \" data-name=\"datetime_2\"  aria-invalid='false' aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_input_text_6' id='label_ff_10_input_text_6' aria-label=\"Lieu de naissance\">Lieu de naissance<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_6\" class=\"ff-el-form-control\" placeholder=\"Lieu de naissance\" data-name=\"input_text_6\" id=\"ff_10_input_text_6\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_2\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_input_text' id='label_ff_10_input_text' aria-label=\"T\u00e9l\u00e9phone\">T\u00e9l\u00e9phone<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"T\u00e9l\u00e9phone\" data-name=\"input_text\" id=\"ff_10_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_input_text_8' id='label_ff_10_input_text_8' aria-label=\"Adresse mail\">Adresse mail<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_8\" class=\"ff-el-form-control\" placeholder=\"Mail\" data-name=\"input_text_8\" id=\"ff_10_input_text_8\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class=\"ff-name-address-wrapper fluent-address\" data-type=\"address-element\" data-name=\"address_2\" ><div class='ff-el-input--content'><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_address_2_address_line_1_' id='label_ff_10_address_2_address_line_1_' aria-label=\"Adresse\">Adresse<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_2[address_line_1]\" id=\"ff_10_address_2_address_line_1_\" class=\"ff-el-form-control\" placeholder=\"Adresse\" data-key_name=\"address_line_1\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_address_2_city_' id='label_ff_10_address_2_city_' aria-label=\"Ville\">Ville <\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_2[city]\" id=\"ff_10_address_2_city_\" class=\"ff-el-form-control\" placeholder=\"Ville\" data-key_name=\"city\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_address_2_zip_' id='label_ff_10_address_2_zip_' aria-label=\"Code postal\">Code postal<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_2[zip]\" id=\"ff_10_address_2_zip_\" class=\"ff-el-form-control\" placeholder=\"Code Postal\" data-key_name=\"zip\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_address_2_country_' id='label_ff_10_address_2_country_' aria-label=\"Pays\">Pays<\/label><\/div><div class='ff-el-input--content'><select name=\"address_2[country]\" id=\"ff_10_address_2_country_\" class=\"ff-el-form-control\" placeholder=\"S\u00e9lectionner le pays\" data-key_name=\"country\" aria-invalid='false' aria-required=true><option value=''>S\u00e9lectionner le pays<\/option><option value='AF' >Afghanistan<\/option><option value='ZA' >Afrique du Sud<\/option><option value='AL' >Albanie<\/option><option value='DZ' >Alg\u00e9rie<\/option><option value='DE' >Allemagne<\/option><option value='AS' >American Samoa<\/option><option value='AD' >Andorre<\/option><option value='AO' >Angola<\/option><option value='AI' >Anguilla<\/option><option value='AQ' >Antarctique<\/option><option value='AG' >Antigua-et-Barbuda<\/option><option value='SA' >Arabie Saoudite<\/option><option value='AR' >Argentine<\/option><option value='AM' >Arm\u00e9nie<\/option><option value='AW' >Aruba<\/option><option value='AU' >Australie<\/option><option value='AT' >Autriche<\/option><option value='AZ' >Azerbaijan<\/option><option value='BS' >Bahamas<\/option><option value='BH' >Bahrain<\/option><option value='BD' >Bangladesh<\/option><option value='BB' >Barbades<\/option><option value='BE' >Belgique<\/option><option value='BZ' >Belize<\/option><option value='BM' >Bermudes<\/option><option value='BT' >Bhoutan<\/option><option value='BY' >Bi\u00e9lorussie<\/option><option value='BO' >Bolivie<\/option><option value='BQ' >Bonaire, Saint-Eustache et Saba<\/option><option value='BA' >Bosnie-Herz\u00e9govine<\/option><option value='BW' >Botswana<\/option><option value='BN' >Brunei<\/option><option value='BR' >Br\u00e9sil<\/option><option value='BG' >Bulgarie<\/option><option value='BF' >Burkina Faso<\/option><option value='BI' >Burundi<\/option><option value='BJ' >B\u00e9nin<\/option><option value='CV' >Cabo Verde<\/option><option value='KH' >Cambodge<\/option><option value='CM' >Cameroun<\/option><option value='CA' >Canada<\/option><option value='CL' >Chili<\/option><option value='CN' >Chine<\/option><option value='CY' >Chypre<\/option><option value='CO' >Colombie<\/option><option value='KM' >Comores<\/option><option value='KP' >Cor\u00e9e du Nord<\/option><option value='KR' >Cor\u00e9e du Sud<\/option><option value='CR' >Costa Rica<\/option><option value='HR' >Croatie<\/option><option value='CU' >Cuba<\/option><option value='CW' >Cura\u00e7ao<\/option><option value='CI' >C\u00f4te-d\u2019Ivoire<\/option><option value='DK' >Danemark<\/option><option value='DJ' >Djibouti<\/option><option value='DM' >Dominique<\/option><option value='ER' >Erythr\u00e9e<\/option><option value='ES' >Espagne<\/option><option value='EE' >Estonie<\/option><option value='SZ' >Eswatini<\/option><option value='US' >Etats-Unis (USA)<\/option><option value='FJ' >Fidji<\/option><option value='FI' >Finlande<\/option><option value='FR' selected>France<\/option><option value='GA' >Gabon<\/option><option value='GM' >Gambie<\/option><option value='GH' >Ghana<\/option><option value='GI' >Gibraltar<\/option><option value='GD' >Grenade<\/option><option value='GL' >Groenland<\/option><option value='GR' >Gr\u00e8ce<\/option><option value='GP' >Guadeloupe<\/option><option value='GU' >Guam<\/option><option value='GT' >Guatemala<\/option><option value='GG' >Guernesey<\/option><option value='GN' >Guin\u00e9e<\/option><option value='GQ' >Guin\u00e9e \u00e9quatoriale<\/option><option value='GW' >Guin\u00e9e-Bissau<\/option><option value='GY' >Guyane<\/option><option value='GF' >Guyane Fran\u00e7aise<\/option><option value='GE' >G\u00e9orgie<\/option><option value='GS' >G\u00e9orgie du Sud \/ \u00eeles Sandwich<\/option><option value='HT' >Ha\u00efti<\/option><option value='HN' >Honduras<\/option><option value='HK' >Hong Kong<\/option><option value='HU' >Hongrie<\/option><option value='IN' >Inde<\/option><option value='ID' >Indon\u00e9sie<\/option><option value='IR' >Iran<\/option><option value='IQ' >Iraq<\/option><option value='IE' >Irlande<\/option><option value='IS' >Islande<\/option><option value='IL' >Isra\u00ebl<\/option><option value='IT' >Italie<\/option><option value='JM' >Jama\u00efque<\/option><option value='JP' >Japon<\/option><option value='JE' >Jersey<\/option><option value='JO' >Jordanie<\/option><option value='KZ' >Kazakhstan<\/option><option value='KE' >Kenya<\/option><option value='KI' >Kiribati<\/option><option value='XK' >Kosovo<\/option><option value='KW' >Kowe\u00eft<\/option><option value='KG' >Kyrgyzstan<\/option><option value='LA' >Laos<\/option><option value='LS' >Lesotho<\/option><option value='LV' >Lettonie<\/option><option value='LB' >Liban<\/option><option value='LR' >Liberia<\/option><option value='LY' >Libye<\/option><option value='LI' >Liechtenstein<\/option><option value='LT' >Lituanie<\/option><option value='LU' >Luxembourg<\/option><option value='MO' >Macao S.A.R., Chine<\/option><option value='MK' >Mac\u00e9doine du Nord<\/option><option value='MG' >Madagascar<\/option><option value='MY' >Malaisie<\/option><option value='MW' >Malawi<\/option><option value='MV' >Maldives<\/option><option value='ML' >Mali<\/option><option value='MT' >Malte<\/option><option value='MA' >Maroc<\/option><option value='MQ' >Martinique<\/option><option value='MU' >Maurice<\/option><option value='MR' >Mauritanie<\/option><option value='YT' >Mayotte<\/option><option value='MX' >Mexique<\/option><option value='FM' >Micron\u00e9sie<\/option><option value='MD' >Moldavie<\/option><option value='MC' >Monaco<\/option><option value='MN' >Mongolie<\/option><option value='ME' >Montenegro<\/option><option value='MS' >Montserrat<\/option><option value='MZ' >Mozambique<\/option><option value='MM' >Myanmar<\/option><option value='NA' >Namibie<\/option><option value='NR' >Nauru<\/option><option value='NI' >Nicaragua<\/option><option value='NE' >Niger<\/option><option value='NG' >Nig\u00e9ria<\/option><option value='NU' >Niue<\/option><option value='NO' >Norv\u00e8ge<\/option><option value='NC' >Nouvelle-Cal\u00e9donie<\/option><option value='NZ' >Nouvelle-Z\u00e9lande<\/option><option value='NP' >N\u00e9pal<\/option><option value='OM' >Oman<\/option><option value='PK' >Pakistan<\/option><option value='PW' >Palaos<\/option><option value='PA' >Panama<\/option><option value='PG' >Papouasie-Nouvelle-Guin\u00e9e<\/option><option value='PY' >Paraguay<\/option><option value='NL' >Pays-Bas<\/option><option value='PH' >Philippines<\/option><option value='PN' >Pitcairn<\/option><option value='PL' >Pologne<\/option><option value='PF' >Polyn\u00e9sie Fran\u00e7aise<\/option><option value='PT' >Portugal<\/option><option value='PR' >Puerto Rico<\/option><option value='PE' >P\u00e9rou<\/option><option value='QA' >Qatar<\/option><option value='RO' >Roumanie<\/option><option value='GB' >Royaume-Uni (UK)<\/option><option value='RU' >Russie<\/option><option value='RW' >Rwanda<\/option><option value='CF' >R\u00e9publique Centrafricaine<\/option><option value='DO' >R\u00e9publique Dominicaine<\/option><option value='CZ' >R\u00e9publique Tch\u00e8que<\/option><option value='CG' >R\u00e9publique du Congo (Brazzaville)<\/option><option value='CD' >R\u00e9publique d\u00e9mocratique du Congo (Kinshasa)<\/option><option value='RE' >R\u00e9union<\/option><option value='EH' >Sahara occidental<\/option><option value='BL' >Saint-Barth\u00e9lemy<\/option><option value='KN' >Saint-Kitts-et-Nevis<\/option><option value='MF' >Saint-Martin (partie fran\u00e7aise)<\/option><option value='SX' >Saint-Martin (partie n\u00e9erlandaise)<\/option><option value='PM' >Saint-Pierre-et-Miquelon<\/option><option value='VC' >Saint-Vincent-et-les-Grenadines<\/option><option value='SH' >Sainte-H\u00e9l\u00e8ne<\/option><option value='LC' >Sainte-Lucie<\/option><option value='SV' >Salvador<\/option><option value='WS' >Samoa<\/option><option value='SM' >San Marino<\/option><option value='ST' >Sao Tom\u00e9-et-Principe<\/option><option value='RS' >Serbie<\/option><option value='SC' >Seychelles<\/option><option value='SL' >Sierra Leone<\/option><option value='SG' >Singapour<\/option><option value='SK' >Slovaquie<\/option><option value='SI' >Slov\u00e9nie<\/option><option value='SO' >Somalie<\/option><option value='SD' >Soudan<\/option><option value='SS' >Soudan du Sud<\/option><option value='LK' >Sri Lanka<\/option><option value='CH' >Suisse<\/option><option value='SR' >Suriname<\/option><option value='SE' >Su\u00e8de<\/option><option value='SJ' >Svalbard et Jan Mayen<\/option><option value='SY' >Syrie<\/option><option value='SN' >S\u00e9n\u00e9gal<\/option><option value='TW' >Taiwan<\/option><option value='TJ' >Tajikistan<\/option><option value='TZ' >Tanzanie<\/option><option value='TD' >Tchad<\/option><option value='TF' >Terres australes et antarctiques fran\u00e7aises<\/option><option value='PS' >Territoire Palestinien<\/option><option value='IO' >Territoire britannique de l&rsquo;oc\u00e9an Indien<\/option><option value='TH' >Thailande<\/option><option value='TL' >Timor-Leste<\/option><option value='TG' >Togo<\/option><option value='TK' >Tokelau<\/option><option value='TO' >Tonga<\/option><option value='TT' >Trinit\u00e9-et-Tobago<\/option><option value='TN' >Tunisie<\/option><option value='TM' >Turkm\u00e9nistan<\/option><option value='TR' >Turquie<\/option><option value='TV' >Tuvalu<\/option><option value='UG' >Uganda<\/option><option value='UA' >Ukraine<\/option><option value='UY' >Uruguay<\/option><option value='UZ' >Uzbekistan<\/option><option value='VU' >Vanuatu<\/option><option value='VA' >Vatican<\/option><option value='VE' >Venezuela<\/option><option value='VN' >Vietnam<\/option><option value='WF' >Wallis et Futuna<\/option><option value='YE' >Yemen<\/option><option value='ZM' >Zambie<\/option><option value='ZW' >Zimbabwe<\/option><option value='EG' >\u00c9gypte<\/option><option value='AE' >\u00c9mirats Arabes Unis<\/option><option value='EC' >\u00c9quateur<\/option><option value='ET' >\u00c9thiopie<\/option><option value='BV' >\u00cele Bouvet<\/option><option value='CX' >\u00cele Christmas<\/option><option value='NF' >\u00cele Norfolk<\/option><option value='IM' >\u00cele de Man<\/option><option value='AX' >\u00celes Aland<\/option><option value='KY' >\u00celes Ca\u00efmans<\/option><option value='CC' >\u00celes Cocos<\/option><option value='CK' >\u00celes Cook<\/option><option value='FK' >\u00celes Falkland<\/option><option value='FO' >\u00celes F\u00e9ro\u00e9<\/option><option value='HM' >\u00celes Heard-et-MacDonald<\/option><option value='MP' >\u00celes Mariannes du Nord<\/option><option value='MH' >\u00celes Marshall<\/option><option value='UM' >\u00celes Mineures \u00e9loign\u00e9es des \u00c9tats-Unis<\/option><option value='SB' >\u00celes Salomon<\/option><option value='TC' >\u00celes Turques et Ca\u00efques<\/option><option value='VI' >\u00celes Vierges am\u00e9ricaines (US)<\/option><option value='VG' >\u00celes Vierges britanniques<\/option><\/select><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_10_dropdown' id='label_ff_10_dropdown' aria-label=\"Nom du gyn\u00e9cologue AMP choisi :\">Nom du gyn\u00e9cologue AMP choisi :<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_10_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_10_dropdown\"><option value=\"\">- Selectionner -<\/option><option value=\"DR AUDE BRUYNEEL\"  >DR AUDE BRUYNEEL<\/option><option value=\"DR JULIETTE DELEPINE\"  >DR JULIETTE DELEPINE<\/option><option value=\"DR ANNE-SOPHIE DELESALLE\"  >DR ANNE-SOPHIE DELESALLE<\/option><option value=\"DR DELPHINE DEROUBAIX\"  >DR DELPHINE DEROUBAIX<\/option><option value=\"DR ANNE-CHRISTINE DESHORGUE\"  >DR ANNE-CHRISTINE DESHORGUE<\/option><option value=\"DR LOUISE RIBIERE\"  >DR LOUISE RIBIERE<\/option><option value=\"Peu importe\"  >Peu importe<\/option><\/select><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\"  aria-label=\"Envoyer\">Envoyer<\/button><\/div><\/fieldset><\/form><div id='fluentform_10_errors' class='ff-errors-in-stack ff_form_instance_10_1 ff-form-loading_errors ff_form_instance_10_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_10_1 = {\"id\":\"10\",\"ajaxUrl\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_10_1\",\"form_id_selector\":\"fluentform_10\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"datetime_2\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"input_text_6\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"input_text_8\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[address_line_1]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[address_line_2]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[city]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[state]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[zip]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"address_2[country]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b353178 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b353178\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a84689 elementor-widget elementor-widget-text-editor\" data-id=\"4a84689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En cliquant sur le bouton \u00ab Envoyer\u00bb, vous consentez au traitement des donn\u00e9es personnelles que vous avez librement fournies, conform\u00e9ment aux dispositions de la\u00a0<a title=\"Donn\u00e9es \u00e0 Caract\u00e8re Personnel\" href=\"https:\/\/amp-hplb-lille.com\/index.php\/colibri-1939\/\" data-entity-type=\"node\" data-entity-uuid=\"bad9df67-7dda-4120-8b5e-a80c24f903aa\" data-entity-substitution=\"canonical\">note d\u2019information Donn\u00e9es personnelles<\/a>.<br \/>Nous vous informons de l\u2019existence de la liste d&rsquo;opposition au d\u00e9marchage t\u00e9l\u00e9phonique \u00abBloctel\u00bb, sur laquelle vous pouvez vous inscrire gratuitement ici :\u00a0<a href=\"https:\/\/www.bloctel.gouv.fr\/\">https:\/\/www.bloctel.gouv.fr\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6636132 elementor-widget elementor-widget-spacer\" data-id=\"6636132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c0575 elementor-widget elementor-widget-google_maps\" data-id=\"b7c0575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=44%20Avenue%20Marx%20Dormoy%20%2C%2059000%20Lille&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"44 Avenue Marx Dormoy , 59000 Lille\"\n\t\t\t\t\taria-label=\"44 Avenue Marx Dormoy , 59000 Lille\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa3c33 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2fa3c33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c62e5b\" data-id=\"1c62e5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bd8df94 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"bd8df94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38933fe\" data-id=\"38933fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74c0b5e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"74c0b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">110 Av. de Dunkerque, 59000 Lille<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">03 20 92 98 04 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 464c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48V200.724a48 48 0 0 1 18.387-37.776c24.913-19.529 45.501-35.365 164.2-121.511C199.412 29.17 232.797-.347 256 .003c23.198-.354 56.596 29.172 73.413 41.433 118.687 86.137 139.303 101.995 164.2 121.512A48 48 0 0 1 512 200.724V464zm-65.666-196.605c-2.563-3.728-7.7-4.595-11.339-1.907-22.845 16.873-55.462 40.705-105.582 77.079-16.825 12.266-50.21 41.781-73.413 41.43-23.211.344-56.559-29.143-73.413-41.43-50.114-36.37-82.734-60.204-105.582-77.079-3.639-2.688-8.776-1.821-11.339 1.907l-9.072 13.196a7.998 7.998 0 0 0 1.839 10.967c22.887 16.899 55.454 40.69 105.303 76.868 20.274 14.781 56.524 47.813 92.264 47.573 35.724.242 71.961-32.771 92.263-47.573 49.85-36.179 82.418-59.97 105.303-76.868a7.998 7.998 0 0 0 1.839-10.967l-9.071-13.196z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">secretariat@amp-hplb-lille.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9b9a1fa\" data-id=\"9b9a1fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eb72d8 elementor-widget elementor-widget-heading\" data-id=\"2eb72d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">menu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f53b628 elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f53b628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accueil<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/projet-parental-2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quels bilans ? <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/quelles-techniques\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quelles techniques ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/fiv-icsi\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comment se passe une FIV ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/mon-quotidien\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comment am\u00e9liorer ma fertilit\u00e9 naturelle ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/preserver-ses-ovocytes\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pr\u00e9server ses ovocytes ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/legislation-et-formalites\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L\u00e9gislation et formalit\u00e9s <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a0500af\" data-id=\"a0500af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4109b0 elementor-widget elementor-widget-heading\" data-id=\"d4109b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">contact<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c445316 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c445316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-de-contact\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prendre rendez-vous<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/f-a-q\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F.A.Q<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amp-hplb-lille.com\/index.php\/nous-trouver\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nous trouver<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c38e774 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c38e774\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1700b3\" data-id=\"d1700b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f8e905 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3f8e905\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-af41140\" data-id=\"af41140\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39aa995 elementor-widget elementor-widget-image\" data-id=\"39aa995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hopital-prive-le-bois-lille.ramsaysante.fr\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"407\" height=\"213\" src=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png\" class=\"attachment-full size-full wp-image-162\" alt=\"\" srcset=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png 407w, https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb-300x157.png 300w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a3965e6\" data-id=\"a3965e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28f48f6 elementor-widget elementor-widget-image\" data-id=\"28f48f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"407\" height=\"213\" src=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-femmily.png\" class=\"attachment-full size-full wp-image-161\" alt=\"\" srcset=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-femmily.png 407w, https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-femmily-300x157.png 300w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-35ea757\" data-id=\"35ea757\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06aa383 elementor-widget elementor-widget-image\" data-id=\"06aa383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cerballiance.fr\/fr\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"407\" height=\"213\" src=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-cerballiance.png\" class=\"attachment-full size-full wp-image-160\" alt=\"\" srcset=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-cerballiance.png 407w, https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-cerballiance-300x157.png 300w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-08ac047\" data-id=\"08ac047\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1af379 elementor-widget elementor-widget-image\" data-id=\"c1af379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.iris-imagerie.fr\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"213\" src=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-iris.png\" class=\"attachment-full size-full wp-image-163\" alt=\"\" srcset=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-iris.png 407w, https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-iris-300x157.png 300w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1472fbb\" data-id=\"1472fbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d821ea1 elementor-shape-circle e-grid-align-right e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"d821ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-animation-grow elementor-repeater-item-0504074\" href=\"https:\/\/www.facebook.com\/polelillemetropole\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-animation-grow elementor-repeater-item-caf132d\" href=\"https:\/\/www.linkedin.com\/company\/hopital-prive-bois\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En cliquant sur le bouton \u00ab Envoyer\u00bb, vous consentez au traitement des donn\u00e9es personnelles que vous avez librement fournies, conform\u00e9ment aux dispositions de la\u00a0note d\u2019information Donn\u00e9es personnelles.Nous vous informons de l\u2019existence de la liste d&rsquo;opposition au d\u00e9marchage t\u00e9l\u00e9phonique \u00abBloctel\u00bb, sur laquelle vous pouvez vous inscrire gratuitement ici :\u00a0https:\/\/www.bloctel.gouv.fr\/ 110 Av. de Dunkerque, 59000 Lille 03 20 92 98 04 secretariat@amp-hplb-lille.com menu Accueil Quels bilans ? Quelles techniques ? Comment se passe une FIV ? Comment am\u00e9liorer ma fertilit\u00e9 naturelle ? Pr\u00e9server ses ovocytes ? L\u00e9gislation et formalit\u00e9s contact Prendre rendez-vous F.A.Q Nous trouver Facebook-f Linkedin-in<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-1740","page","type-page","status-publish","hentry"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\" \/>\n<meta property=\"og:description\" content=\"En cliquant sur le bouton \u00ab Envoyer\u00bb, vous consentez au traitement des donn\u00e9es personnelles que vous avez librement fournies, conform\u00e9ment aux dispositions de la\u00a0note d\u2019information Donn\u00e9es personnelles.Nous vous informons de l\u2019existence de la liste d&rsquo;opposition au d\u00e9marchage t\u00e9l\u00e9phonique \u00abBloctel\u00bb, sur laquelle vous pouvez vous inscrire gratuitement ici :\u00a0https:\/\/www.bloctel.gouv.fr\/ 110 Av. de Dunkerque, 59000 Lille 03 20 92 98 04 secretariat@amp-hplb-lille.com menu Accueil Quels bilans ? Quelles techniques ? Comment se passe une FIV ? Comment am\u00e9liorer ma fertilit\u00e9 naturelle ? Pr\u00e9server ses ovocytes ? L\u00e9gislation et formalit\u00e9s contact Prendre rendez-vous F.A.Q Nous trouver Facebook-f Linkedin-in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/\" \/>\n<meta property=\"og:site_name\" content=\"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T10:02:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"407\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/\",\"url\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/\",\"name\":\"Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-hplb.png\",\"datePublished\":\"2024-02-26T15:25:11+00:00\",\"dateModified\":\"2026-02-25T10:02:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-hplb.png\",\"contentUrl\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-hplb.png\",\"width\":407,\"height\":213},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/index.php\\\/formulaire-femme-seule\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/amp-hplb-lille.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formulaire femme seule\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#website\",\"url\":\"https:\\\/\\\/amp-hplb-lille.com\\\/\",\"name\":\"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\",\"description\":\"H\u00f4pital priv\u00e9 Le Bois - Lille\",\"publisher\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amp-hplb-lille.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#organization\",\"name\":\"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\",\"url\":\"https:\\\/\\\/amp-hplb-lille.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-amp-hplb-lille.png\",\"contentUrl\":\"https:\\\/\\\/amp-hplb-lille.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-amp-hplb-lille.png\",\"width\":1080,\"height\":1080,\"caption\":\"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation\"},\"image\":{\"@id\":\"https:\\\/\\\/amp-hplb-lille.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/","og_locale":"fr_FR","og_type":"article","og_title":"Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","og_description":"En cliquant sur le bouton \u00ab Envoyer\u00bb, vous consentez au traitement des donn\u00e9es personnelles que vous avez librement fournies, conform\u00e9ment aux dispositions de la\u00a0note d\u2019information Donn\u00e9es personnelles.Nous vous informons de l\u2019existence de la liste d&rsquo;opposition au d\u00e9marchage t\u00e9l\u00e9phonique \u00abBloctel\u00bb, sur laquelle vous pouvez vous inscrire gratuitement ici :\u00a0https:\/\/www.bloctel.gouv.fr\/ 110 Av. de Dunkerque, 59000 Lille 03 20 92 98 04 secretariat@amp-hplb-lille.com menu Accueil Quels bilans ? Quelles techniques ? Comment se passe une FIV ? Comment am\u00e9liorer ma fertilit\u00e9 naturelle ? Pr\u00e9server ses ovocytes ? L\u00e9gislation et formalit\u00e9s contact Prendre rendez-vous F.A.Q Nous trouver Facebook-f Linkedin-in","og_url":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/","og_site_name":"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","article_modified_time":"2026-02-25T10:02:28+00:00","og_image":[{"width":407,"height":213,"url":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/","url":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/","name":"Formulaire femme seule - Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","isPartOf":{"@id":"https:\/\/amp-hplb-lille.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/#primaryimage"},"image":{"@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/#primaryimage"},"thumbnailUrl":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png","datePublished":"2024-02-26T15:25:11+00:00","dateModified":"2026-02-25T10:02:28+00:00","breadcrumb":{"@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/#primaryimage","url":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png","contentUrl":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/logo-hplb.png","width":407,"height":213},{"@type":"BreadcrumbList","@id":"https:\/\/amp-hplb-lille.com\/index.php\/formulaire-femme-seule\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/amp-hplb-lille.com\/"},{"@type":"ListItem","position":2,"name":"Formulaire femme seule"}]},{"@type":"WebSite","@id":"https:\/\/amp-hplb-lille.com\/#website","url":"https:\/\/amp-hplb-lille.com\/","name":"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","description":"H\u00f4pital priv\u00e9 Le Bois - Lille","publisher":{"@id":"https:\/\/amp-hplb-lille.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amp-hplb-lille.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/amp-hplb-lille.com\/#organization","name":"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation","url":"https:\/\/amp-hplb-lille.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amp-hplb-lille.com\/#\/schema\/logo\/image\/","url":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/cropped-logo-amp-hplb-lille.png","contentUrl":"https:\/\/amp-hplb-lille.com\/wp-content\/uploads\/2024\/01\/cropped-logo-amp-hplb-lille.png","width":1080,"height":1080,"caption":"Assistance M\u00e9dicale \u00e0 la Procr\u00e9ation"},"image":{"@id":"https:\/\/amp-hplb-lille.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/pages\/1740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/comments?post=1740"}],"version-history":[{"count":16,"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/pages\/1740\/revisions"}],"predecessor-version":[{"id":2330,"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/pages\/1740\/revisions\/2330"}],"wp:attachment":[{"href":"https:\/\/amp-hplb-lille.com\/index.php\/wp-json\/wp\/v2\/media?parent=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}